{"id":2768,"date":"2023-01-07T00:00:00","date_gmt":"2023-01-06T23:00:00","guid":{"rendered":"http:\/\/hermandadelperdonmadrid.es\/?p=2768"},"modified":"2025-04-14T12:27:41","modified_gmt":"2025-04-14T11:27:41","slug":"adios-al-papa-sabio","status":"publish","type":"post","link":"https:\/\/hermandadelperdonmadrid.es\/index.php\/2023\/01\/07\/adios-al-papa-sabio\/","title":{"rendered":"Adi\u00f3s al Papa Sabio"},"content":{"rendered":"<p style=\"text-align: justify;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-2773 alignleft\" src=\"https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-1.jpg?resize=220%2C192&#038;ssl=1\" alt=\"\" width=\"220\" height=\"192\" srcset=\"https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-1.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-1.jpg?resize=300%2C263&amp;ssl=1 300w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-1.jpg?resize=768%2C672&amp;ssl=1 768w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/>Hace apenas una semana que conocimos la noticia del fallecimiento Benedicto XVI, el Papa que fue llamado a sustituir al tan querido San Juan Pablo II (cuyo funeral presidi\u00f3 como Decano del Colegio Cardenalicio), el Papa de la JMJ de Madrid y la consagraci\u00f3n de la Sagrada Familia de Barcelona y el primer pont\u00edfice en seiscientos a\u00f1os en dejar su puesto al considerar que no estaba preparado para continuar al frente de la Iglesia.<\/p>\n<p style=\"text-align: justify;\">Desde que el Papa Francisco nos pidi\u00f3 tener muy presente al Papa Em\u00e9rito en nuestras oraciones, muchos comenzaron a releer, recapitular y resumir algunas de las ense\u00f1anzas y, por qu\u00e9 no, del legado de Ratzinger, atribuy\u00e9ndole el apelativo del \u201cPapa Sabio\u201d.<\/p>\n<p style=\"text-align: justify;\">Joseph Ratzinger naci\u00f3 en Bavaria (Alemania) el 16 de abril de 1927, en el seno de una familia humilde de agricultores y artesanos.\u00a0 Creci\u00f3 y se form\u00f3 en Traunstein, una peque\u00f1a localidad cerca de la frontera con Austria, a treinta kil\u00f3metros de Salzburgo, viviendo de cerca la crueldad de los nazis y su hostilidad contra la Iglesia Cat\u00f3lica.<\/p>\n<p style=\"text-align: justify;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-2784 aligncenter\" src=\"https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-11.jpg?resize=540%2C315&#038;ssl=1\" alt=\"\" width=\"540\" height=\"315\" srcset=\"https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-11.jpg?w=1030&amp;ssl=1 1030w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-11.jpg?resize=300%2C175&amp;ssl=1 300w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-11.jpg?resize=1024%2C597&amp;ssl=1 1024w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-11.jpg?resize=768%2C447&amp;ssl=1 768w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/>Fue ordenado sacerdote en junio de 1951, y empez\u00f3 su labor docente un a\u00f1o despu\u00e9s. Precisamente, sus grandes conocimientos teol\u00f3gicos le llevaron a participar como asesor del cardenal Joseph Frings, arzobispo de Colonia, en el Concilio Vaticano II, as\u00ed como a desempe\u00f1ar importantes cargos al servicio de la Conferencia Episcopal Alemana y la Comisi\u00f3n Teol\u00f3gica Internacional.<\/p>\n<p style=\"text-align: justify;\">El 25 de marzo de 1977, el Papa Pablo VI lo nombr\u00f3 arzobispo de Munich y Freising. Tres meses m\u00e1s tarde, ser\u00eda proclamado cardenal. Juan Pablo II, por su parte, lo nombr\u00f3 Prefecto de la Congregaci\u00f3n para la Doctrina de la Fe, presidente de la Pontificia Comisi\u00f3n B\u00edblica y de la Comisi\u00f3n Teol\u00f3gica Internacional, presidente de la Comisi\u00f3n para la preparaci\u00f3n del Catecismo de la Iglesia Cat\u00f3lica (1992) y miembro de varias Secretar\u00edas de Estado.<\/p>\n<p style=\"text-align: justify;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-2783 aligncenter\" src=\"https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-10.jpg?resize=460%2C259&#038;ssl=1\" alt=\"\" width=\"460\" height=\"259\" srcset=\"https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-10.jpg?w=770&amp;ssl=1 770w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-10.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-10.jpg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"auto, (max-width: 460px) 100vw, 460px\" \/>Tras la muerte de Juan Pablo II, y pasados dos d\u00edas y medio de c\u00f3nclave, Ratzinger obtuvo los votos necesarios para convertirse en el 265\u00ba pont\u00edfice de la Iglesia Cat\u00f3lica. Su primer viaje lo realiz\u00f3 a Bari, el d\u00eda del Corpus Christi, para clausurar el Congreso Eucar\u00edstico Nacional Italiano y presidir un encuentro con la Iglesia Ortodoxa Oriental.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-2781\" src=\"https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-8.jpg?resize=258%2C185&#038;ssl=1\" alt=\"\" width=\"258\" height=\"185\" srcset=\"https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-8.jpg?w=1960&amp;ssl=1 1960w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-8.jpg?resize=300%2C215&amp;ssl=1 300w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-8.jpg?resize=1024%2C735&amp;ssl=1 1024w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-8.jpg?resize=768%2C551&amp;ssl=1 768w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-8.jpg?resize=1536%2C1102&amp;ssl=1 1536w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-8.jpg?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 258px) 100vw, 258px\" \/><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-2782\" src=\"https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-9.jpg?resize=329%2C185&#038;ssl=1\" alt=\"\" width=\"329\" height=\"185\" srcset=\"https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-9.jpg?w=644&amp;ssl=1 644w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-9.jpg?resize=300%2C169&amp;ssl=1 300w\" sizes=\"auto, (max-width: 329px) 100vw, 329px\" \/><\/p>\n<hr \/>\n<p style=\"text-align: justify;\">Antes de su renuncia, Benedicto XVI viaj\u00f3 a Espa\u00f1a en tres ocasiones. El primero de sus viajes tuvo lugar en julio de 2006, cuando visit\u00f3 Valencia con ocasi\u00f3n del Encuentro Mundial de las Familias. El pont\u00edfice presidi\u00f3 una misa multitudinaria en la explanada de la Ciudad de las Artes y las Ciencias, en la que aprovech\u00f3 para recordar la importancia de la familia como instituci\u00f3n intermedia entre el individuo y la sociedad: \u201c<em>Un peque\u00f1o n\u00facleo familiar puede encontrar obst\u00e1culos dif\u00edciles de superar si se encuentra aislado del resto de sus parientes y amistades. Por ello, la comunidad eclesial tiene la responsabilidad de ofrecer acompa\u00f1amiento, est\u00edmulo y alimento espiritual que fortalezca la cohesi\u00f3n familiar, sobre todo en las pruebas o momentos cr\u00edticos\u201d.<\/em><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\" wp-image-2770 aligncenter\" src=\"https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-2.jpeg?resize=570%2C321&#038;ssl=1\" alt=\"\" width=\"570\" height=\"321\" srcset=\"https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-2.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-2.jpeg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-2.jpeg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-2.jpeg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"auto, (max-width: 570px) 100vw, 570px\" \/><\/p>\n<p style=\"text-align: justify;\">Cinco a\u00f1os m\u00e1s tarde, en noviembre de 2010,\u00a0Benedicto XVI regres\u00f3 a Espa\u00f1a para visitar Santiago de Compostela (con motivo del\u00a0a\u00f1o Santo Compostelano) y Barcelona, para la consagraci\u00f3n de la Bas\u00edlica de la Sagrada Familia.<em> \u201cNo se puede dar culto a Dios sin velar por el hombre su hijo y no se sirve al hombre sin preguntarse por qui\u00e9n es su Padre y responderle a la pregunta por \u00e9l\u201d <\/em>fueron algunas de sus palabras en la homil\u00eda que pronunci\u00f3 en la plaza del Obradoiro.<\/p>\n<p style=\"text-align: justify;\">Por otro lado, en la Santa Misa de consagraci\u00f3n del templo de la Sagrada Familia, el Papa se\u00f1al\u00f3 que \u201ce<em>l \u00fanico Cristo funda la \u00fanica Iglesia; \u00c9l es la roca sobre la que se cimienta nuestra fe. Apoyados en esa fe, busquemos juntos mostrar al mundo el rostro de Dios, que es amor y el \u00fanico que puede responder al anhelo de plenitud del hombre. \u00c9sa es la gran tarea, mostrar a todos que Dios es Dios de paz y no de violencia, de libertad y no de coacci\u00f3n, de concordia y no de discordia\u201d. <\/em><\/p>\n<p style=\"text-align: justify;\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignnone size-full wp-image-2769\" src=\"https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-1.heic?w=640&#038;ssl=1\" alt=\"\" \/><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\" wp-image-2774 alignleft\" src=\"https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-4.jpg?resize=225%2C197&#038;ssl=1\" alt=\"\" width=\"225\" height=\"197\" srcset=\"https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-4.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-4.jpg?resize=300%2C263&amp;ssl=1 300w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-4.jpg?resize=768%2C672&amp;ssl=1 768w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/>Pero, sin lugar a duda, el acontecimiento que m\u00e1s trascendencia ha tenido para los cat\u00f3licos espa\u00f1oles (y para nuestra Hermandad) fue la Jornada Mundial de la Juventud de 2011, celebrada en Madrid del 18 al 21 de agosto. M\u00e1s de dos millones de personas participamos en los distintos actos programados a lo largo de esos d\u00edas, cuyo momento culmen tuvo lugar en la vigilia del aer\u00f3dromo de Cuatro Vientos, presidida por la Custodia de Arfe de la Catedral de Toledo y en la que no falt\u00f3 ni el viento ni la lluvia.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\" wp-image-2771 aligncenter\" src=\"https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-3.jpeg?resize=540%2C304&#038;ssl=1\" alt=\"\" width=\"540\" height=\"304\" srcset=\"https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-3.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-3.jpeg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-3.jpeg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-3.jpeg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/p>\n<blockquote>\n<p style=\"text-align: justify;\">\u201cQueridos j\u00f3venes, permitidme que, como Sucesor de Pedro, os invite a fortalecer esta fe que se nos ha transmitido desde los Ap\u00f3stoles, a poner a Cristo, el Hijo de Dios, en el centro de vuestra vida. Pero permitidme tambi\u00e9n que os recuerde que seguir a Jes\u00fas en la fe es caminar con \u00c9l en la comuni\u00f3n de la Iglesia. No se puede seguir a Jes\u00fas en solitario. Quien cede a la tentaci\u00f3n de ir \u00abpor su cuenta\u00bb o de vivir la fe seg\u00fan la mentalidad individualista, que predomina en la sociedad, corre el riesgo de no encontrar nunca a Jesucristo, o de acabar siguiendo una imagen falsa de \u00c9l\u201d.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\" wp-image-2775 alignleft\" src=\"https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-5.jpg?resize=185%2C185&#038;ssl=1\" alt=\"\" width=\"185\" height=\"185\" srcset=\"https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-5.jpg?w=680&amp;ssl=1 680w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-5.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2023\/01\/Benedicto-5.jpg?resize=150%2C150&amp;ssl=1 150w\" sizes=\"auto, (max-width: 185px) 100vw, 185px\" \/>El 11 de febrero de 2013 Benedicto XVI anunci\u00f3 su renuncia, que se har\u00eda efectiva el 28 de febrero. El pasado s\u00e1bado, 31 de diciembre, nos lleg\u00f3 la noticia esperada, aunque no por ello menos triste, de su fallecimiento, a los noventa y cinco a\u00f1os de edad. Desde hace unas horas reposa en la que fue la tumba de Juan Pablo II, tras un funeral sobrio presidido por el Papa Francisco y oficiado por el cardenal decano del Colegio Cardenalicio, Giovanni Battista Re.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace apenas una semana que conocimos la noticia del fallecimiento Benedicto XVI, el Papa que fue llamado a sustituir al tan querido San Juan Pablo II (cuyo funeral presidi\u00f3 como Decano del Colegio Cardenalicio), el Papa de la JMJ de &hellip; <a href=\"https:\/\/hermandadelperdonmadrid.es\/index.php\/2023\/01\/07\/adios-al-papa-sabio\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2768","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8GJlT-IE","_links":{"self":[{"href":"https:\/\/hermandadelperdonmadrid.es\/index.php\/wp-json\/wp\/v2\/posts\/2768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hermandadelperdonmadrid.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hermandadelperdonmadrid.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hermandadelperdonmadrid.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hermandadelperdonmadrid.es\/index.php\/wp-json\/wp\/v2\/comments?post=2768"}],"version-history":[{"count":4,"href":"https:\/\/hermandadelperdonmadrid.es\/index.php\/wp-json\/wp\/v2\/posts\/2768\/revisions"}],"predecessor-version":[{"id":3602,"href":"https:\/\/hermandadelperdonmadrid.es\/index.php\/wp-json\/wp\/v2\/posts\/2768\/revisions\/3602"}],"wp:attachment":[{"href":"https:\/\/hermandadelperdonmadrid.es\/index.php\/wp-json\/wp\/v2\/media?parent=2768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hermandadelperdonmadrid.es\/index.php\/wp-json\/wp\/v2\/categories?post=2768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hermandadelperdonmadrid.es\/index.php\/wp-json\/wp\/v2\/tags?post=2768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}