{"id":3345,"date":"2024-07-20T12:20:12","date_gmt":"2024-07-20T11:20:12","guid":{"rendered":"http:\/\/hermandadelperdonmadrid.es\/?p=3345"},"modified":"2024-08-02T12:25:41","modified_gmt":"2024-08-02T11:25:41","slug":"3345","status":"publish","type":"post","link":"https:\/\/hermandadelperdonmadrid.es\/index.php\/2024\/07\/20\/3345\/","title":{"rendered":"Acompa\u00f1ando a la Patrona"},"content":{"rendered":"<p style=\"text-align: justify;\">Ernesto Rodr\u00edguez, pregonero de la Virgen del Carmen de Algeciras, pronunci\u00f3 las siguientes palabras en su preg\u00f3n del a\u00f1o 2018:<\/p>\n<p style=\"text-align: justify;\"><em>\u201cNecesitados estamos, m\u00e1s que nunca, Virgen del Carmen, de tu amor, de esa luz que retienes en la mirada como cuando abrazamos un recuerdo; y de caminar con tu Hijo. Es Cristo que perdona en silencio por las calles de nuestras vidas\u201d<\/em><\/p>\n<p style=\"text-align: justify;\">Como es tradici\u00f3n, el pasado 16 de julio acompa\u00f1amos a Nuestra Se\u00f1ora del Carmen en la procesi\u00f3n anual con motivo de su fiesta lit\u00fargica. Un d\u00eda antes, estuvimos presentes en la Funci\u00f3n Principal de su Hermandad, con sede en la misma parroquia que nuestra corporaci\u00f3n.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\" wp-image-3346 aligncenter\" src=\"https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2024\/08\/El-Carmen-2024-1-scaled.jpg?resize=630%2C420&#038;ssl=1\" alt=\"\" width=\"630\" height=\"420\" srcset=\"https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2024\/08\/El-Carmen-2024-1-scaled.jpg?w=2560&amp;ssl=1 2560w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2024\/08\/El-Carmen-2024-1-scaled.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2024\/08\/El-Carmen-2024-1-scaled.jpg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2024\/08\/El-Carmen-2024-1-scaled.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2024\/08\/El-Carmen-2024-1-scaled.jpg?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2024\/08\/El-Carmen-2024-1-scaled.jpg?resize=2048%2C1365&amp;ssl=1 2048w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2024\/08\/El-Carmen-2024-1-scaled.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2024\/08\/El-Carmen-2024-1-scaled.jpg?w=1920&amp;ssl=1 1920w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><\/p>\n<p style=\"text-align: justify;\">El pasado mes de mayo, la Sagrada Imagen de la Virgen del Carmen de San Ram\u00f3n fue nombrada Patrona del distrito de Puente de Vallecas, recibiendo del concejal D. \u00c1ngel Ni\u00f1o Quesada sus atributos como edil.<\/p>\n<p style=\"text-align: justify;\">Al atardecer del martes 16 de julio, al t\u00e9rmino de la Eucarist\u00eda presidida por el Excmo. Y Rvdmo. Sr. Obispo auxiliar de Madrid, D. Vicente Mart\u00ednez, la Virgen volvi\u00f3 a cruzar el dintel de la parroquia para encontrarse con sus vecinos. Formando parte del cortejo, nuestra Hermandad estuvo representada por un grupo de hermanos, encabezados por el estandarte flanqueado por dos faroles, llevados por miembros del grupo joven.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\" wp-image-3347 aligncenter\" src=\"https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2024\/08\/El-Carmen-2024-2-scaled.jpg?resize=640%2C427&#038;ssl=1\" alt=\"\" width=\"640\" height=\"427\" srcset=\"https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2024\/08\/El-Carmen-2024-2-scaled.jpg?w=2560&amp;ssl=1 2560w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2024\/08\/El-Carmen-2024-2-scaled.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2024\/08\/El-Carmen-2024-2-scaled.jpg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2024\/08\/El-Carmen-2024-2-scaled.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2024\/08\/El-Carmen-2024-2-scaled.jpg?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2024\/08\/El-Carmen-2024-2-scaled.jpg?resize=2048%2C1365&amp;ssl=1 2048w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2024\/08\/El-Carmen-2024-2-scaled.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/hermandadelperdonmadrid.es\/wp-content\/uploads\/2024\/08\/El-Carmen-2024-2-scaled.jpg?w=1920&amp;ssl=1 1920w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p style=\"text-align: justify;\">Pasadas las diez de la noche la Virgen, a los sones de la Agrupaci\u00f3n Musical La Soledad de Coslada, entr\u00f3 de nuevo en el templo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ernesto Rodr\u00edguez, pregonero de la Virgen del Carmen de Algeciras, pronunci\u00f3 las siguientes palabras en su preg\u00f3n del a\u00f1o 2018: \u201cNecesitados estamos, m\u00e1s que nunca, Virgen del Carmen, de tu amor, de esa luz que retienes en la mirada como &hellip; <a href=\"https:\/\/hermandadelperdonmadrid.es\/index.php\/2024\/07\/20\/3345\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3345","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/s8GJlT-3345","_links":{"self":[{"href":"https:\/\/hermandadelperdonmadrid.es\/index.php\/wp-json\/wp\/v2\/posts\/3345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hermandadelperdonmadrid.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hermandadelperdonmadrid.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hermandadelperdonmadrid.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hermandadelperdonmadrid.es\/index.php\/wp-json\/wp\/v2\/comments?post=3345"}],"version-history":[{"count":2,"href":"https:\/\/hermandadelperdonmadrid.es\/index.php\/wp-json\/wp\/v2\/posts\/3345\/revisions"}],"predecessor-version":[{"id":3349,"href":"https:\/\/hermandadelperdonmadrid.es\/index.php\/wp-json\/wp\/v2\/posts\/3345\/revisions\/3349"}],"wp:attachment":[{"href":"https:\/\/hermandadelperdonmadrid.es\/index.php\/wp-json\/wp\/v2\/media?parent=3345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hermandadelperdonmadrid.es\/index.php\/wp-json\/wp\/v2\/categories?post=3345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hermandadelperdonmadrid.es\/index.php\/wp-json\/wp\/v2\/tags?post=3345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}